{"id":952,"date":"2018-12-10T22:52:14","date_gmt":"2018-12-10T22:52:14","guid":{"rendered":"https:\/\/blog.infraspeak.com\/?p=952"},"modified":"2023-02-07T17:15:23","modified_gmt":"2023-02-07T17:15:23","slug":"novidades-do-infraspeak-49","status":"publish","type":"post","link":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/","title":{"rendered":"Novidades do Infraspeak \u00b7 6-Dez-2018"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p dir=\"ltr\">Criar um edif\u00edcio costuma ser um processo demorado \u2014 por exemplo, sabia que a catedral de S\u00e3o Bas\u00edlio (Moscovo, R\u00fassia) <strong>demorou 123 anos a ser criada<\/strong>, desde o in\u00edcio da sua constru\u00e7\u00e3o em 1555? Ou que a Sagrada Fam\u00edlia, em Barcelona, se encontra em constru\u00e7\u00e3o h\u00e1 136 anos e a conclus\u00e3o \u00e9 esperada <strong>apenas em 2026<\/strong>, centen\u00e1rio da morte de Gaud\u00ed?<\/p>\n<p><strong>E qual \u00e9 a rela\u00e7\u00e3o disto com o Infraspeak?<\/strong><\/p>\n<p dir=\"ltr\">Pois bem, \u00e9 seguro dizer que <strong>se Gaud\u00ed tivesse o Infraspeak e um smartphone Andoid na altura, teria criado a Sagrada Fam\u00edlia em 2 minutos<\/strong>. Na verdade, todos os clientes Infraspeak podem criar a Sagrada Fam\u00edlia (ou qualquer outro edif\u00edcio) em 2 minutos e at\u00e9 decidir quem pode geri-la, entre outras coisas.<\/p>\n<h2 dir=\"ltr\">Cria\u00e7\u00e3o de edif\u00edcios e clientes no Android<\/h2>\n<p dir=\"ltr\">A partir de agora \u00e9 muito mais f\u00e1cil criar e configurar\u00a0<strong>novos clientes e edif\u00edcios<\/strong> no Infraspeak, em qualquer lugar \u2014 por exemplo, enquanto se desloca entre esses mesmos edif\u00edcios para mapear todas as instala\u00e7\u00f5es \u2014 pois \u00e9 poss\u00edvel faz\u00ea-lo <strong>diretamente na app Android<\/strong> do Infraspeak.<\/p>\n<p dir=\"ltr\">Na app, basta entrar em &#8220;Adicionar cliente&#8221; \u00bb escolher o cliente no qual pretende adicionar um novo edif\u00edcio \u00bb clicar no bot\u00e3o &#8220;Ver Edif\u00edcios&#8221; \u00bb bot\u00e3o &#8220;+&#8221; para adicionar um novo edif\u00edcio.<\/p>\n<h2 dir=\"ltr\">Novas configura\u00e7\u00f5es de permiss\u00f5es<\/h2>\n<h2 dir=\"ltr\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-12350 size-800 aligncenter\" style=\"font-size: 16px; font-weight: 400;\" src=\"http:\/\/home.infraspeak.com\/wp-content\/uploads\/2018\/12\/config_acesso-800x420.png\" alt=\"Screenshot Infraspeak\" width=\"800\" height=\"420\" \/><\/h2>\n<p>Ao criar novos utilizadores do Infraspeak, \u00e9 agora poss\u00edvel definir novas configura\u00e7\u00f5es de <strong>permiss\u00f5<\/strong><strong>es<\/strong><strong>\u00a0de acesso a \u00e1reas de administra\u00e7\u00e3o<\/strong> \u2014 decida se um utilizador pode ou n\u00e3o gerir tipos de equipamentos, tipos de \u00e1reas de avarias, entre outras op\u00e7\u00f5es.<\/p>\n<p>Para isto, entre no separador &#8220;Administra\u00e7\u00e3o&#8221; \u00bb &#8220;Utilizadores e Contactos&#8221; barra lateral esquerda \u00bb entrar num utilizador ou em &#8220;Novo Utilizador&#8221; \u00bb abrir o separador &#8220;Configura\u00e7\u00f5es \u00bb as novas configura\u00e7\u00f5es estar\u00e3o na linha &#8220;Administra\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saiba como criar edif\u00edcios\/clientes na aplica\u00e7\u00e3o Android e veja quais s\u00e3o as novas configura\u00e7\u00f5es de permiss\u00f5es para os utilizadores.<\/p>\n","protected":false},"author":54,"featured_media":953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","_wp_rev_ctl_limit":""},"categories":[334],"tags":[78,190],"class_list":["post-952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-plataforma","tag-novidades","tag-produto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novidades do Infraspeak \u00b7 6-Dez-2018 &#8226; Infraspeak Blog<\/title>\n<meta name=\"description\" content=\"Saiba como criar edif\u00edcios\/clientes na aplica\u00e7\u00e3o Android e veja quais s\u00e3o as novas configura\u00e7\u00f5es de permiss\u00f5es para os utilizadores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novidades do Infraspeak \u00b7 6-Dez-2018 &#8226; Infraspeak Blog\" \/>\n<meta property=\"og:description\" content=\"Saiba como criar edif\u00edcios\/clientes na aplica\u00e7\u00e3o Android e veja quais s\u00e3o as novas configura\u00e7\u00f5es de permiss\u00f5es para os utilizadores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/\" \/>\n<meta property=\"og:site_name\" content=\"Infraspeak Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infraspeakmaintenance\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-10T22:52:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-07T17:15:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/config_acesso-800x420.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Infraspeak Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infraspeak\" \/>\n<meta name=\"twitter:site\" content=\"@infraspeak\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Infraspeak Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/\"},\"author\":{\"name\":\"Infraspeak Team\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/b53887f01881a658b4cc1bf25f2d4377\"},\"headline\":\"Novidades do Infraspeak \u00b7 6-Dez-2018\",\"datePublished\":\"2018-12-10T22:52:14+00:00\",\"dateModified\":\"2023-02-07T17:15:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/\"},\"wordCount\":305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/config_acesso-800x420.png\",\"keywords\":[\"novidades\",\"produto\"],\"articleSection\":[\"Infraspeak\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/\",\"name\":\"Novidades do Infraspeak \u00b7 6-Dez-2018 &#8226; Infraspeak Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/config_acesso-800x420.png\",\"datePublished\":\"2018-12-10T22:52:14+00:00\",\"dateModified\":\"2023-02-07T17:15:23+00:00\",\"description\":\"Saiba como criar edif\u00edcios\\\/clientes na aplica\u00e7\u00e3o Android e veja quais s\u00e3o as novas configura\u00e7\u00f5es de permiss\u00f5es para os utilizadores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/config_acesso-800x420.png\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/config_acesso-800x420.png\",\"width\":800,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-do-infraspeak-49\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.infraspeak.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novidades do Infraspeak \u00b7 6-Dez-2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/\",\"name\":\"Infraspeak Blog\",\"description\":\"All About Maintenance and Facilities Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\",\"name\":\"Infraspeak\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/is-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/is-logo@2x.png\",\"width\":544,\"height\":180,\"caption\":\"Infraspeak\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infraspeakmaintenance\",\"https:\\\/\\\/x.com\\\/infraspeak\",\"https:\\\/\\\/www.instagram.com\\\/infraspeak\\\/\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/infraspeak\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCOdjKyhSD9RJbRhuP-S8Avw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/b53887f01881a658b4cc1bf25f2d4377\",\"name\":\"Infraspeak Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"caption\":\"Infraspeak Team\"},\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/author\\\/infraspeakteam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novidades do Infraspeak \u00b7 6-Dez-2018 &#8226; Infraspeak Blog","description":"Saiba como criar edif\u00edcios\/clientes na aplica\u00e7\u00e3o Android e veja quais s\u00e3o as novas configura\u00e7\u00f5es de permiss\u00f5es para os utilizadores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/","og_locale":"pt_PT","og_type":"article","og_title":"Novidades do Infraspeak \u00b7 6-Dez-2018 &#8226; Infraspeak Blog","og_description":"Saiba como criar edif\u00edcios\/clientes na aplica\u00e7\u00e3o Android e veja quais s\u00e3o as novas configura\u00e7\u00f5es de permiss\u00f5es para os utilizadores.","og_url":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/","og_site_name":"Infraspeak Blog","article_publisher":"https:\/\/www.facebook.com\/infraspeakmaintenance","article_published_time":"2018-12-10T22:52:14+00:00","article_modified_time":"2023-02-07T17:15:23+00:00","og_image":[{"width":800,"height":420,"url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/config_acesso-800x420.png","type":"image\/png"}],"author":"Infraspeak Team","twitter_card":"summary_large_image","twitter_creator":"@infraspeak","twitter_site":"@infraspeak","twitter_misc":{"Escrito por":"Infraspeak Team","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/#article","isPartOf":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/"},"author":{"name":"Infraspeak Team","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/person\/b53887f01881a658b4cc1bf25f2d4377"},"headline":"Novidades do Infraspeak \u00b7 6-Dez-2018","datePublished":"2018-12-10T22:52:14+00:00","dateModified":"2023-02-07T17:15:23+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/"},"wordCount":305,"commentCount":0,"publisher":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/config_acesso-800x420.png","keywords":["novidades","produto"],"articleSection":["Infraspeak"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/","url":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/","name":"Novidades do Infraspeak \u00b7 6-Dez-2018 &#8226; Infraspeak Blog","isPartOf":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/#primaryimage"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/config_acesso-800x420.png","datePublished":"2018-12-10T22:52:14+00:00","dateModified":"2023-02-07T17:15:23+00:00","description":"Saiba como criar edif\u00edcios\/clientes na aplica\u00e7\u00e3o Android e veja quais s\u00e3o as novas configura\u00e7\u00f5es de permiss\u00f5es para os utilizadores.","breadcrumb":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/#primaryimage","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/config_acesso-800x420.png","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/config_acesso-800x420.png","width":800,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-do-infraspeak-49\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.infraspeak.com\/"},{"@type":"ListItem","position":2,"name":"Novidades do Infraspeak \u00b7 6-Dez-2018"}]},{"@type":"WebSite","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#website","url":"https:\/\/blog.infraspeak.com\/pt-pt\/","name":"Infraspeak Blog","description":"All About Maintenance and Facilities Management","publisher":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.infraspeak.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization","name":"Infraspeak","url":"https:\/\/blog.infraspeak.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2018\/11\/is-logo@2x.png","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2018\/11\/is-logo@2x.png","width":544,"height":180,"caption":"Infraspeak"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infraspeakmaintenance","https:\/\/x.com\/infraspeak","https:\/\/www.instagram.com\/infraspeak\/","http:\/\/www.linkedin.com\/company\/infraspeak","https:\/\/www.youtube.com\/channel\/UCOdjKyhSD9RJbRhuP-S8Avw"]},{"@type":"Person","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/person\/b53887f01881a658b4cc1bf25f2d4377","name":"Infraspeak Team","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","caption":"Infraspeak Team"},"url":"https:\/\/blog.infraspeak.com\/pt-pt\/author\/infraspeakteam\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/posts\/952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=952"}],"version-history":[{"count":1,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/posts\/952\/revisions"}],"predecessor-version":[{"id":957,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/posts\/952\/revisions\/957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/media\/953"}],"wp:attachment":[{"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}