{"id":869,"date":"2017-11-27T18:29:30","date_gmt":"2017-11-27T18:29:30","guid":{"rendered":"https:\/\/blog.infraspeak.com\/?p=869"},"modified":"2023-02-07T17:16:23","modified_gmt":"2023-02-07T17:16:23","slug":"novidades-produto-30","status":"publish","type":"post","link":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/","title":{"rendered":"Novidades do Produto #30"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Entre as novidades a sair do forno est\u00e3o: uma gest\u00e3o de avarias mais simples e \u00e1gil, o Infraspeak Direct ainda mais eficiente e completo e muito mais.<\/p>\n<h3>AVARIAS 2.0: SEU NOVO M\u00d3DULO DE GEST\u00c3O DE AVARIAS<\/h3>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-7093\" src=\"http:\/\/home.infraspeak.com\/wp-content\/uploads\/2017\/11\/IS-avarias1.jpg\" alt=\"\" width=\"2560\" height=\"1600\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-7115\" src=\"http:\/\/home.infraspeak.com\/wp-content\/uploads\/2017\/11\/IS-avarias2b.jpg\" alt=\"\" width=\"1920\" height=\"1080\" \/><\/p>\n<p>Respondendo a pedidos de diversos clientes, renovamos o m\u00f3dulo de Gest\u00e3o de Avarias. A vers\u00e3o 2.0 conta com melhorias em termos de design e disposi\u00e7\u00e3o da informa\u00e7\u00e3o, que deixam o trabalho mais r\u00e1pido, f\u00e1cil e intuitivo.<\/p>\n<p>Na interface do gestor, as avarias t\u00eam um novo formato. Ao visualizar os detalhes de uma avaria, o gestor tem acesso a um ecr\u00e3 mais organizado, com uma disposi\u00e7\u00e3o flu\u00edda e com a possibilidade de editar cada um dos campos, aprovar ou pausar diretamente naquela janela. Tamb\u00e9m pode associar equipamentos, tarefas, utilizadores respons\u00e1veis, e mais.<\/p>\n<h4>Melhor gest\u00e3o das prioridades<\/h4>\n<p><img decoding=\"async\" class=\"size-full wp-image-7092 alignleft\" src=\"http:\/\/home.infraspeak.com\/wp-content\/uploads\/2017\/11\/IS-prioridades.png\" alt=\"\" width=\"92\" height=\"161\" \/>Devido aos diversos tipos de ecr\u00e3 e interfaces que o Infraspeak est\u00e1 a atuar, fizemos um pequeno ajuste para que as prioridades nas avarias sejam perfeitamente identific\u00e1veis em qualquer dispositivo. Deixamos de usar o Amarelo e mudamos a escala de cores para: Azul (Prioridade 1), Verde (Prioridade 2), Laranja (Prioridade 3) e Vermelho (Prioridade 4). Os nomes das prioridades s\u00e3o agora edit\u00e1veis, permitindo a personaliza\u00e7\u00e3o pelos administradores.<\/p>\n<p>&nbsp;<\/p>\n<h4>Observa\u00e7\u00f5es e Caracter\u00edsticas<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7097 size-thumbnail\" src=\"http:\/\/home.infraspeak.com\/wp-content\/uploads\/2017\/11\/IS-obs-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/>Ao adicionar equipamentos a avarias na interface do gestor, este consegue ver as observa\u00e7\u00f5es e caracter\u00edsticas t\u00e9cnicas relacionadas no mesmo ecr\u00e3, tornando esse processo mais simples.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>Motivos de Pausa Personaliz\u00e1veis<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7091 alignleft\" src=\"http:\/\/home.infraspeak.com\/wp-content\/uploads\/2017\/11\/IS-motivosdepausa2.jpg\" alt=\"\" width=\"170\" height=\"80\" \/>Os motivos de pausa de uma avaria podem agora ser personaliz\u00e1veis pelos administradores, o que permite uma maior adapta\u00e7\u00e3o do Infraspeak aos processo de cada empresa, bem como decidir quais utilizadores \u00e9 que podem ver cada motivo de pausa.<\/p>\n<p>&nbsp;<\/p>\n<h4>Passagens de estado mais \u00e1geis<\/h4>\n<p>As passagens de estado das avarias, de \u201cPor aprovar\u201d at\u00e9 \u201cFechada\u201d, agora contam com um processo mais \u00e1gil da parte do gestor, e rapidamente podem passar do primeiro estado para o \u00faltimo. Tamb\u00e9m passa a ser poss\u00edvel alterar o motivo de pausa sem a necessidade de aprovar ou mesmo iniciar a avaria.<\/p>\n<h4>Juntar-se \u00e0 Avaria<\/h4>\n<p>Assim como nos trabalhos agendados, agora os t\u00e9cnicos podem juntar-se \u00e0s avarias no Infraspeak Mobile. Assim h\u00e1 um controlo mais preciso de quanto tempo cada utilizador envolvido numa avaria dedica \u00e0 sua resolu\u00e7\u00e3o.<\/p>\n<h3>INFRASPEAK DIRECT MAIS PRECISO NO REGISTO DE AVARIAS<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7096 size-medium\" src=\"http:\/\/home.infraspeak.com\/wp-content\/uploads\/2017\/11\/IS-directphoto-blog-221x300.jpg\" alt=\"\" width=\"221\" height=\"300\" \/>Os utilizadores do Infraspeak Direct tamb\u00e9m ganham melhorias na sua aplica\u00e7\u00e3o. \u00c0 semelhan\u00e7a do que j\u00e1 acontecia na app para t\u00e9cnicos, agora \u00e9 poss\u00edvel adicionar fotos \u00e0 avaria reportada durante o processo de &#8220;reportar avaria&#8221;. Outra novidade \u00e9 a possibilidade de, ao associar um local a uma avaria, fazer uma pesquisa pelos locais, deixando ainda mais r\u00e1pido e preciso o processo de registo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>MELHORIAS DE PERFORMANCE EM TODAS AS INTERFACES<\/h3>\n<ul>\n<li>Agora as fotos em tarefas e medi\u00e7\u00f5es aparecem nos documentos dos trabalhos e no hist\u00f3rico do equipamento.<br \/>\nA listagem de eventos planeados aparecem nas ocorr\u00eancias dos Trabalhos Preventivos na interface do gestor.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a a nova gest\u00e3o de avarias, mais simples e \u00e1gil, o Infraspeak Direct ainda mais eficiente e completo e muitas outras novidades.<\/p>\n","protected":false},"author":54,"featured_media":870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","_wp_rev_ctl_limit":""},"categories":[334],"tags":[78,190],"class_list":["post-869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-plataforma","tag-novidades","tag-produto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novidades do Produto #30 &#8226; Infraspeak Blog<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a a nova gest\u00e3o de avarias, mais simples e \u00e1gil, o Infraspeak Direct ainda mais eficiente e completo e muitas outras novidades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novidades do Produto #30 &#8226; Infraspeak Blog\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a a nova gest\u00e3o de avarias, mais simples e \u00e1gil, o Infraspeak Direct ainda mais eficiente e completo e muitas outras novidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Infraspeak Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infraspeakmaintenance\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-27T18:29:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-07T17:16:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/IS-avariasblog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Infraspeak Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infraspeak\" \/>\n<meta name=\"twitter:site\" content=\"@infraspeak\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Infraspeak Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/\"},\"author\":{\"name\":\"Infraspeak Team\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/b53887f01881a658b4cc1bf25f2d4377\"},\"headline\":\"Novidades do Produto #30\",\"datePublished\":\"2017-11-27T18:29:30+00:00\",\"dateModified\":\"2023-02-07T17:16:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/\"},\"wordCount\":515,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/IS-avariasblog.jpg\",\"keywords\":[\"novidades\",\"produto\"],\"articleSection\":[\"Infraspeak\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/\",\"name\":\"Novidades do Produto #30 &#8226; Infraspeak Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/IS-avariasblog.jpg\",\"datePublished\":\"2017-11-27T18:29:30+00:00\",\"dateModified\":\"2023-02-07T17:16:23+00:00\",\"description\":\"Conhe\u00e7a a nova gest\u00e3o de avarias, mais simples e \u00e1gil, o Infraspeak Direct ainda mais eficiente e completo e muitas outras novidades.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/IS-avariasblog.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/IS-avariasblog.jpg\",\"width\":1250,\"height\":833},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/novidades-produto-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.infraspeak.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novidades do Produto #30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/\",\"name\":\"Infraspeak Blog\",\"description\":\"All About Maintenance and Facilities Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\",\"name\":\"Infraspeak\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/is-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/is-logo@2x.png\",\"width\":544,\"height\":180,\"caption\":\"Infraspeak\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infraspeakmaintenance\",\"https:\\\/\\\/x.com\\\/infraspeak\",\"https:\\\/\\\/www.instagram.com\\\/infraspeak\\\/\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/infraspeak\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCOdjKyhSD9RJbRhuP-S8Avw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/b53887f01881a658b4cc1bf25f2d4377\",\"name\":\"Infraspeak Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"caption\":\"Infraspeak Team\"},\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/author\\\/infraspeakteam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novidades do Produto #30 &#8226; Infraspeak Blog","description":"Conhe\u00e7a a nova gest\u00e3o de avarias, mais simples e \u00e1gil, o Infraspeak Direct ainda mais eficiente e completo e muitas outras novidades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/","og_locale":"pt_PT","og_type":"article","og_title":"Novidades do Produto #30 &#8226; Infraspeak Blog","og_description":"Conhe\u00e7a a nova gest\u00e3o de avarias, mais simples e \u00e1gil, o Infraspeak Direct ainda mais eficiente e completo e muitas outras novidades.","og_url":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/","og_site_name":"Infraspeak Blog","article_publisher":"https:\/\/www.facebook.com\/infraspeakmaintenance","article_published_time":"2017-11-27T18:29:30+00:00","article_modified_time":"2023-02-07T17:16:23+00:00","og_image":[{"width":1250,"height":833,"url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/IS-avariasblog.jpg","type":"image\/jpeg"}],"author":"Infraspeak Team","twitter_card":"summary_large_image","twitter_creator":"@infraspeak","twitter_site":"@infraspeak","twitter_misc":{"Escrito por":"Infraspeak Team","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/#article","isPartOf":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/"},"author":{"name":"Infraspeak Team","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/person\/b53887f01881a658b4cc1bf25f2d4377"},"headline":"Novidades do Produto #30","datePublished":"2017-11-27T18:29:30+00:00","dateModified":"2023-02-07T17:16:23+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/"},"wordCount":515,"commentCount":0,"publisher":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/IS-avariasblog.jpg","keywords":["novidades","produto"],"articleSection":["Infraspeak"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/","url":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/","name":"Novidades do Produto #30 &#8226; Infraspeak Blog","isPartOf":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/#primaryimage"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/IS-avariasblog.jpg","datePublished":"2017-11-27T18:29:30+00:00","dateModified":"2023-02-07T17:16:23+00:00","description":"Conhe\u00e7a a nova gest\u00e3o de avarias, mais simples e \u00e1gil, o Infraspeak Direct ainda mais eficiente e completo e muitas outras novidades.","breadcrumb":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/#primaryimage","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/IS-avariasblog.jpg","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/01\/IS-avariasblog.jpg","width":1250,"height":833},{"@type":"BreadcrumbList","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/novidades-produto-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.infraspeak.com\/"},{"@type":"ListItem","position":2,"name":"Novidades do Produto #30"}]},{"@type":"WebSite","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#website","url":"https:\/\/blog.infraspeak.com\/pt-pt\/","name":"Infraspeak Blog","description":"All About Maintenance and Facilities Management","publisher":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.infraspeak.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization","name":"Infraspeak","url":"https:\/\/blog.infraspeak.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2018\/11\/is-logo@2x.png","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2018\/11\/is-logo@2x.png","width":544,"height":180,"caption":"Infraspeak"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infraspeakmaintenance","https:\/\/x.com\/infraspeak","https:\/\/www.instagram.com\/infraspeak\/","http:\/\/www.linkedin.com\/company\/infraspeak","https:\/\/www.youtube.com\/channel\/UCOdjKyhSD9RJbRhuP-S8Avw"]},{"@type":"Person","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/person\/b53887f01881a658b4cc1bf25f2d4377","name":"Infraspeak Team","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","caption":"Infraspeak Team"},"url":"https:\/\/blog.infraspeak.com\/pt-pt\/author\/infraspeakteam\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/posts\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":1,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/posts\/869\/revisions"}],"predecessor-version":[{"id":874,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/posts\/869\/revisions\/874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/media\/870"}],"wp:attachment":[{"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}