{"id":11493,"date":"2021-11-15T18:38:08","date_gmt":"2021-11-15T18:38:08","guid":{"rendered":"https:\/\/blog.infraspeak.com\/?p=11493"},"modified":"2023-02-07T17:20:01","modified_gmt":"2023-02-07T17:20:01","slug":"manutencao-predial-desafios","status":"publish","type":"post","link":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/","title":{"rendered":"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span style=\"font-weight: 400;\">Quando falamos em manuten\u00e7\u00e3o, \u00e9 f\u00e1cil pensarmos apenas na manuten\u00e7\u00e3o de m\u00e1quinas de produ\u00e7\u00e3o ou em grandes equipamentos. Nem sempre falamos da manuten\u00e7\u00e3o do pr\u00f3prio edif\u00edcio, embora seja <\/span><b>uma das melhores formas de valorizar o im\u00f3vel e continuar a oferecer uma experi\u00eancia de excel\u00eancia ao usu\u00e1rio. <\/b><span style=\"font-weight: 400;\">Para falar sobre esse tema, recuperamos uma agrad\u00e1vel conversa com <\/span><a href=\"https:\/\/sinergiatc.eng.br\/engclaudiocelino\/\"><span style=\"font-weight: 400;\">Cl\u00e1udio Celino<\/span><\/a><span style=\"font-weight: 400;\">, da empresa Sinergia, especialista em manuten\u00e7\u00e3o predial com mais de 20 anos de experi\u00eancia no setor.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><iframe title=\"Os Desafios da Manuten\u00e7\u00e3o Predial \u2219 Talks at Infraspeak\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/6EI-VOM-Yt0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h2><b>O estado das coisas: qual \u00e9 o principal desafio da manuten\u00e7\u00e3o predial?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Em Facility Management, o<em> outsourcing<\/em> \u00e9 a norma.<\/span><b> A <\/b><b>McKinsey<\/b><b> estima que <a href=\"https:\/\/www.mckinsey.com\/business-functions\/operations\/our-insights\/six-emerging-trends-in-facilities-management-sourcing\">esse modelo j\u00e1 representa mais de metade do mercado de FM <\/a><\/b><span style=\"font-weight: 400;\">e a tend\u00eancia \u00e9 que as empresas entreguem todo o FM a um s\u00f3 parceiro. Mas, por enquanto, a maioria ainda lida com v\u00e1rios prestadores \u2013 por exemplo, uma empresa para a limpeza di\u00e1ria, outra para a limpeza da fachada, outra para os sistemas de seguran\u00e7a, outra para a manuten\u00e7\u00e3o das escadas rolantes, e por a\u00ed em diante.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como \u00e9 dif\u00edcil para os gestores (internos) controlar tudo o que cada prestador faz, \u201ctransformamos tudo em um s\u00f3 pagador\u201d, afirma Cl\u00e1udio Celino. E \u00e9 exatamente esse o primeiro grande desafio da manuten\u00e7\u00e3o predial: <\/span><b>a falta de controle.<\/b><span style=\"font-weight: 400;\"> Mas, quais s\u00e3o as causas desta falta de controle? E quais as suas ramifica\u00e7\u00f5es? Segundo a sua experi\u00eancia, isso acontece por tr\u00eas fatores:\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Falta de pessoas<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O primeiro fator que contribui para o descontrole \u00e9 a falta de pessoas. Os departamentos de Facility Management costumam ter falta de pessoal<\/span><i><span style=\"font-weight: 400;\">. <\/span><\/i><span style=\"font-weight: 400;\">A manuten\u00e7\u00e3o das m\u00e1quinas necess\u00e1rias ao<\/span><i><span style=\"font-weight: 400;\"> core business<\/span><\/i><span style=\"font-weight: 400;\"> \u00e9 priorit\u00e1ria, mas o resto \u00e9 encarado como um \u201cgasto\u201d. Por isso, h\u00e1 falta de pessoas focadas na gest\u00e3o das instala\u00e7\u00f5es ou em recolher, analisar e auditar dados \u00fateis para a manuten\u00e7\u00e3o predial.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Falta de sistemas<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O segundo fator \u00e9 a falta de sistemas. Mesmo que cada prestador use um software e tenha uma boa organiza\u00e7\u00e3o interna, raramente h\u00e1 um sistema que centralize todas as informa\u00e7\u00f5es. Por isso, \u00e9 muito dif\u00edcil para o gestor acompanhar o que cada prestador est\u00e1 fazendo, obter informa\u00e7\u00f5es atualizadas, ter uma percep\u00e7\u00e3o clara dos trabalhos pendentes e cruzar dados.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Falta de processos<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Por \u00faltimo, as falhas acontecem nos processos. Mesmo quando exista alguma consciencializa\u00e7\u00e3o sobre o FM e um sistema onde inserir dados, n\u00e3o h\u00e1 um processo bem definido. Por exemplo, pode ser que n\u00e3o existam\u00a0<\/span><span style=\"font-weight: 400;\">pontos de recolha de informa\u00e7\u00f5es bem definidos.<\/span><span style=\"font-weight: 400;\"> Ou a equipe nem sempre registra a abertura e o encerramento dos trabalhos. O resultado \u00e9 um volume de informa\u00e7\u00f5es pouco confi\u00e1veis e quase sempre desatualizadas.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"font-weight: 400;\">Em rela\u00e7\u00e3o aos \u00faltimos dois pontos, o relat\u00f3rio da McKinsey recorda que o<\/span><b> Facility Management est\u00e1 atr\u00e1s de outros setores, incluindo a manuten\u00e7\u00e3o de equipamentos, tanto em maturidade digital como na penetra\u00e7\u00e3o de tecnologia. <\/b><span style=\"font-weight: 400;\">Apesar de n\u00e3o faltarem op\u00e7\u00f5es, <\/span><b>h\u00e1 falta de compet\u00eancias digitais, o que muitas vezes n\u00e3o \u00e9 uma prioridade para a alta dire\u00e7\u00e3o das empresas, que focam na redu\u00e7\u00e3o de custos.\u00a0\u00a0<\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">As plataformas inteligentes, capazes de integrar com in\u00fameras ferramentas, s\u00e3o uma das op\u00e7\u00f5es mais disruptivas para o setor. Ao reunir toda a informa\u00e7\u00e3o, elas permitem recuperar o controle das opera\u00e7\u00f5es di\u00e1rias. Mas isso n\u00e3o \u00e9 tudo. Existem ainda dois grandes desafios na manuten\u00e7\u00e3o predial, que influenciam e s\u00e3o influenciados por esta falta de controle: a <\/span><b>falta de tempo<\/b><span style=\"font-weight: 400;\"> e a <\/span><b>falta de valoriza\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\">. Ambos podem melhorar significativamente com a ajuda da tecnologia.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Um ciclo vicioso: porque o Facility Management n\u00e3o \u00e9 valorizado?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A gest\u00e3o de infraestruturas, o acompanhamento das obras e das opera\u00e7\u00f5es di\u00e1rias exigem tempo, aten\u00e7\u00e3o e dedica\u00e7\u00e3o. Mas, como j\u00e1 dissemos, a maioria das empresas n\u00e3o prioriza o FM. Muitas vezes, h\u00e1 apenas uma pessoa supervisionando toda a manuten\u00e7\u00e3o. Isso faz com que ela tenha que focar nos servi\u00e7os imprescind\u00edveis, fazendo com que o resto acabe por ficar para segundo, terceiro ou quarto plano.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Obviamente, a constante falta de tempo acaba levando \u00e0 falta de controle. Por outro lado, como nunca h\u00e1 tempo para implementar sistemas nem processos de controle, o FM acaba exigindo ainda mais tempo do que seria desej\u00e1vel. Aqui j\u00e1 come\u00e7amos a entrar em um loop de inefici\u00eancia e desorganiza\u00e7\u00e3o, que traz as suas pr\u00f3prias consequ\u00eancias.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Como n\u00e3o h\u00e1 tempo para fazer todas as tarefas nem processos de controle, se torna imposs\u00edvel demonstrar resultados. <\/b><span style=\"font-weight: 400;\">\u201cO que n\u00e3o se mede n\u00e3o se gerencia\u201d, como j\u00e1 ouvimos tantas vezes. <\/span><b>Como fica dif\u00edcil demonstrar resultados, ou provar que o FM influencia os resultados da empresa, as chefias continuam negligenciando o setor e insistindo na redu\u00e7\u00e3o de custos.<\/b><span style=\"font-weight: 400;\"> \u00c9 este ciclo que leva \u00e0 \u201credu\u00e7\u00e3o de custos\u201d e \u00e0 \u201cfalta de prioriza\u00e7\u00e3o\u201d apontadas no relat\u00f3rio da McKinsey.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Como justificar o investimento em tecnologia de Facility Management\u00a0<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ironicamente, a redu\u00e7\u00e3o de custos pode sair cara. Com uma ferramenta apropriada para FM, o gestor consegue controlar o custo mensal da manuten\u00e7\u00e3o, as despesas com manuten\u00e7\u00e3o corretiva, inserir informa\u00e7\u00f5es sobre o que investiu, o retorno que obteve e at\u00e9 a <\/span><a href=\"https:\/\/blog.infraspeak.com\/pt-br\/depreciacao-em-manutencao\/\"><span style=\"font-weight: 400;\">deprecia\u00e7\u00e3o dos ativos<\/span><\/a><span style=\"font-weight: 400;\">. Ao longo do tempo, \u00e9 poss\u00edvel ter uma no\u00e7\u00e3o da vida \u00fatil de cada equipamento, prever se precisam ser substitu\u00eddos se precisam de manuten\u00e7\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em outras palavras: a recolha sistem\u00e1tica de dados traz <\/span><b>previsibilidade. <\/b><span style=\"font-weight: 400;\">Como explica Cl\u00e1udio Celino, \u201c<\/span><b>com essa previsibilidade, j\u00e1 sei quando preciso substituir aquele equipamento. Consigo planejar a manuten\u00e7\u00e3o de maneira mais eficaz e reduzir o n\u00famero de manuten\u00e7\u00f5es corretivas. Mas, mantendo sempre o mesmo n\u00famero de manuten\u00e7\u00f5es preventivas.<\/b><span style=\"font-weight: 400;\">\u201d\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Para o cliente, tamb\u00e9m \u00e9 muito melhor. <\/span><b>\u201c\u00c9 preciso demonstrar que a manuten\u00e7\u00e3o foi feita \u2013 quando, por quem e durante quanto tempo \u2013 <\/b><b>e\u00a0<\/b><b>que foi feito de acordo com o plano de manuten\u00e7\u00e3o\u201d.<\/b><span style=\"font-weight: 400;\"> Dessa forma, \u00e9 muito mais f\u00e1cil demonstrar o trabalho do prestador de servi\u00e7os e destacar o papel do FM na <\/span><b>valoriza\u00e7\u00e3o do edif\u00edcio e da experi\u00eancia do usu\u00e1rio<\/b><span style=\"font-weight: 400;\">. Esta \u00faltima \u00e9 uma das principais tend\u00eancias da Ind\u00fastria 5.0, que se chega de maneira mais humanizada.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>\u201cPrecisamos de uma sinergia entre os sistemas, as pessoas e os processos\u201d, <\/b><span style=\"font-weight: 400;\">conclui. <\/span><b>\u00a0<\/b><span style=\"font-weight: 400;\">Dito assim, n\u00e3o faltam raz\u00f5es para embarcar em uma transforma\u00e7\u00e3o digital e inverter o cen\u00e1rio atual. \u00c9 o momento da manuten\u00e7\u00e3o predial deixar de ser uma batalha perdida!<\/span><\/p>\n<p><a href=\"https:\/\/infraspeak.com\/pt-br\/demo\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-3725\" src=\"http:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/11\/PT-Demo-Banner.png\" alt=\"\" width=\"1694\" height=\"582\" srcset=\"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/11\/PT-Demo-Banner.png 1694w, https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/11\/PT-Demo-Banner-300x103.png 300w, https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/11\/PT-Demo-Banner-768x264.png 768w, https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2019\/11\/PT-Demo-Banner-1024x352.png 1024w\" sizes=\"(max-width: 1694px) 100vw, 1694px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Facility Management est\u00e1 atr\u00e1s de outros setores, incluindo a manuten\u00e7\u00e3o de equipamentos, tanto em maturidade digital como na penetra\u00e7\u00e3o de tecnologia. Porqu\u00ea?<\/p>\n","protected":false},"author":54,"featured_media":9350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","_wp_rev_ctl_limit":""},"categories":[368,366],"tags":[],"class_list":["post-11493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-facilities","category-manutencao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d &#8226; Infraspeak Blog<\/title>\n<meta name=\"description\" content=\"O Facility Management e a Manuten\u00e7\u00e3o Predial est\u00e3o atr\u00e1s da manuten\u00e7\u00e3o de equipamentos tanto em maturidade digital como na penetra\u00e7\u00e3o de tecnologia. Porqu\u00ea?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d &#8226; Infraspeak Blog\" \/>\n<meta property=\"og:description\" content=\"O Facility Management e a Manuten\u00e7\u00e3o Predial est\u00e3o atr\u00e1s da manuten\u00e7\u00e3o de equipamentos tanto em maturidade digital como na penetra\u00e7\u00e3o de tecnologia. Porqu\u00ea?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/\" \/>\n<meta property=\"og:site_name\" content=\"Infraspeak Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infraspeakmaintenance\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-15T18:38:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-07T17:20:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2021\/04\/rsz_adobestock_254529308-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Infraspeak Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infraspeak\" \/>\n<meta name=\"twitter:site\" content=\"@infraspeak\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Infraspeak Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/\"},\"author\":{\"name\":\"Infraspeak Team\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/b53887f01881a658b4cc1bf25f2d4377\"},\"headline\":\"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d\",\"datePublished\":\"2021-11-15T18:38:08+00:00\",\"dateModified\":\"2023-02-07T17:20:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/\"},\"wordCount\":1147,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/rsz_adobestock_254529308-min.jpg\",\"articleSection\":[\"Gest\u00e3o de Facilities\",\"Manuten\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/\",\"name\":\"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d &#8226; Infraspeak Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/rsz_adobestock_254529308-min.jpg\",\"datePublished\":\"2021-11-15T18:38:08+00:00\",\"dateModified\":\"2023-02-07T17:20:01+00:00\",\"description\":\"O Facility Management e a Manuten\u00e7\u00e3o Predial est\u00e3o atr\u00e1s da manuten\u00e7\u00e3o de equipamentos tanto em maturidade digital como na penetra\u00e7\u00e3o de tecnologia. Porqu\u00ea?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/rsz_adobestock_254529308-min.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/rsz_adobestock_254529308-min.jpg\",\"width\":1280,\"height\":625,\"caption\":\"IoT in building automation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/manutencao-predial-desafios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.infraspeak.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/\",\"name\":\"Infraspeak Blog\",\"description\":\"All About Maintenance and Facilities Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\",\"name\":\"Infraspeak\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/is-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/is-logo@2x.png\",\"width\":544,\"height\":180,\"caption\":\"Infraspeak\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infraspeakmaintenance\",\"https:\\\/\\\/x.com\\\/infraspeak\",\"https:\\\/\\\/www.instagram.com\\\/infraspeak\\\/\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/infraspeak\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCOdjKyhSD9RJbRhuP-S8Avw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/b53887f01881a658b4cc1bf25f2d4377\",\"name\":\"Infraspeak Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"caption\":\"Infraspeak Team\"},\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-br\\\/author\\\/infraspeakteam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d &#8226; Infraspeak Blog","description":"O Facility Management e a Manuten\u00e7\u00e3o Predial est\u00e3o atr\u00e1s da manuten\u00e7\u00e3o de equipamentos tanto em maturidade digital como na penetra\u00e7\u00e3o de tecnologia. Porqu\u00ea?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/","og_locale":"pt_BR","og_type":"article","og_title":"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d &#8226; Infraspeak Blog","og_description":"O Facility Management e a Manuten\u00e7\u00e3o Predial est\u00e3o atr\u00e1s da manuten\u00e7\u00e3o de equipamentos tanto em maturidade digital como na penetra\u00e7\u00e3o de tecnologia. Porqu\u00ea?","og_url":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/","og_site_name":"Infraspeak Blog","article_publisher":"https:\/\/www.facebook.com\/infraspeakmaintenance","article_published_time":"2021-11-15T18:38:08+00:00","article_modified_time":"2023-02-07T17:20:01+00:00","og_image":[{"width":1280,"height":625,"url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2021\/04\/rsz_adobestock_254529308-min.jpg","type":"image\/jpeg"}],"author":"Infraspeak Team","twitter_card":"summary_large_image","twitter_creator":"@infraspeak","twitter_site":"@infraspeak","twitter_misc":{"Escrito por":"Infraspeak Team","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/#article","isPartOf":{"@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/"},"author":{"name":"Infraspeak Team","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/person\/b53887f01881a658b4cc1bf25f2d4377"},"headline":"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d","datePublished":"2021-11-15T18:38:08+00:00","dateModified":"2023-02-07T17:20:01+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/"},"wordCount":1147,"publisher":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2021\/04\/rsz_adobestock_254529308-min.jpg","articleSection":["Gest\u00e3o de Facilities","Manuten\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/","url":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/","name":"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d &#8226; Infraspeak Blog","isPartOf":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/#primaryimage"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2021\/04\/rsz_adobestock_254529308-min.jpg","datePublished":"2021-11-15T18:38:08+00:00","dateModified":"2023-02-07T17:20:01+00:00","description":"O Facility Management e a Manuten\u00e7\u00e3o Predial est\u00e3o atr\u00e1s da manuten\u00e7\u00e3o de equipamentos tanto em maturidade digital como na penetra\u00e7\u00e3o de tecnologia. Porqu\u00ea?","breadcrumb":{"@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/#primaryimage","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2021\/04\/rsz_adobestock_254529308-min.jpg","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2021\/04\/rsz_adobestock_254529308-min.jpg","width":1280,"height":625,"caption":"IoT in building automation"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.infraspeak.com\/pt-br\/manutencao-predial-desafios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.infraspeak.com\/"},{"@type":"ListItem","position":2,"name":"Manuten\u00e7\u00e3o Predial: \u201co que n\u00e3o se mede, n\u00e3o se gerencia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#website","url":"https:\/\/blog.infraspeak.com\/pt-pt\/","name":"Infraspeak Blog","description":"All About Maintenance and Facilities Management","publisher":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.infraspeak.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization","name":"Infraspeak","url":"https:\/\/blog.infraspeak.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2018\/11\/is-logo@2x.png","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2018\/11\/is-logo@2x.png","width":544,"height":180,"caption":"Infraspeak"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infraspeakmaintenance","https:\/\/x.com\/infraspeak","https:\/\/www.instagram.com\/infraspeak\/","http:\/\/www.linkedin.com\/company\/infraspeak","https:\/\/www.youtube.com\/channel\/UCOdjKyhSD9RJbRhuP-S8Avw"]},{"@type":"Person","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/person\/b53887f01881a658b4cc1bf25f2d4377","name":"Infraspeak Team","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","caption":"Infraspeak Team"},"url":"https:\/\/blog.infraspeak.com\/pt-br\/author\/infraspeakteam\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/posts\/11493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/comments?post=11493"}],"version-history":[{"count":7,"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/posts\/11493\/revisions"}],"predecessor-version":[{"id":13569,"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/posts\/11493\/revisions\/13569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/media\/9350"}],"wp:attachment":[{"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/media?parent=11493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/categories?post=11493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.infraspeak.com\/pt-br\/wp-json\/wp\/v2\/tags?post=11493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}