{"id":10627,"date":"2021-09-09T16:26:24","date_gmt":"2021-09-09T16:26:24","guid":{"rendered":"https:\/\/blog.infraspeak.com\/?p=10627"},"modified":"2023-04-26T15:31:14","modified_gmt":"2023-04-26T15:31:14","slug":"digitalizacion-de-activos-industriales-lubricados","status":"publish","type":"post","link":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/","title":{"rendered":"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p style=\"text-align: left;\"><strong><em>La Digitalizaci\u00f3n de Activos Industriales Lubricados.<\/em>\u00a0La sexta de las #25VoiceTalks organizadas mensualmente en la comunidad IFM.\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\">En este episiodio, sobre la <strong>digitalizaci\u00f3n de activos industriales lubricados<\/strong>, hablamos con Guillermo Mir\u00f3, sobre la influencia de la revoluci\u00f3n digital y la adopci\u00f3n de las nuevas tecnolog\u00edas. Los administradores de activos generalmente han tardado m\u00e1s en aprovechar esta oportunidad. La mayor\u00eda de las empresas se centran tradicionalmente en la gesti\u00f3n de costes, en lugar de crear valor a trav\u00e9s de la digitalizaci\u00f3n de sus operaciones.<\/p>\n<h3><a href=\"https:\/\/intelligenceformaintenance.com\/es\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-13486 size-large\" src=\"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/03\/ES_Banner_CTA_Blog_Community-1-1024x351.png\" alt=\"\" width=\"800\" height=\"274\" srcset=\"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/03\/ES_Banner_CTA_Blog_Community-1-1024x351.png 1024w, https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/03\/ES_Banner_CTA_Blog_Community-1-300x103.png 300w, https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/03\/ES_Banner_CTA_Blog_Community-1-768x264.png 768w, https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/03\/ES_Banner_CTA_Blog_Community-1.png 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/h3>\n<h2 style=\"text-align: left;\">Digitalizaci\u00f3n de los activos industriales lubricados<\/h2>\n<p style=\"text-align: left;\">Todos los equipos de las plantas industriales no requieren lubricaci\u00f3n. Este tipo de <strong>mantenimiento<\/strong>\u00a0relacionado con la <strong>lubricaci\u00f3n<\/strong> nos referimos al <strong>mantenimiento predictivo<\/strong>. Existen diferentes tecnologi\u00e1s; como vibraciones, an\u00e1lisis de aceite, termograf\u00eda. Debido a la revoluci\u00f3n digital han surgido diferentes tecnolog\u00edas que ayudan a realizar mejoras, como pueden ser los sensores. <a href=\"https:\/\/open.spotify.com\/episode\/6mpGBFNZoxVRsMVOdcJgqC?si=h4PFbyBlQDWn4l0nVIiDuQ&amp;dl_branch=1\">Conoce m\u00e1s sobre este tipo de sensores en el podcast<\/a>.<\/p>\n<h2 style=\"text-align: left;\">Tendencias y oportunidades<\/h2>\n<p class=\"p1\" style=\"text-align: left;\">La r\u00e1pida respuesta y planificaci\u00f3n que habilitan este tipo de herramientas anal\u00edticas, posibilitan que se puedan realizar\u00a0esas <strong>acciones predictivas.\u00a0<\/strong>En el entorno industrial, el <a href=\"https:\/\/blog.infraspeak.com\/es\/mantenimiento-predictivo\/\">mantenimiento predictivo<\/a> de las m\u00e1quinas y equipos permite reducir su tiempo de parada, incrementar su vida \u00fatil, reducir los costes de su mantenimiento, disminuir las mermas de los productos fabricados, as\u00ed como reducir el impacto medioambiental.<\/p>\n<p style=\"text-align: left;\">La lubricaci\u00f3n depende del tipo de sector, por ejemplo en el sector energ\u00e9tico o de la automoci\u00f3n, son empresas que cuentan con todo lo que es necesario para desarrollar la digitalizaci\u00f3n. Al contar con infraestructuras como Edge o Cloud computing para la recopilaci\u00f3n de datos, son capaces de desarrollar una estrategia de digitalizaci\u00f3n en este tipo de <strong>activos indsutriales lubricados.\u00a0<\/strong><\/p>\n<h2 style=\"text-align: left;\">Sensores y plataformas inteligentes<\/h2>\n<p style=\"text-align: left;\"><em>\u00abUno de los mayores problemas identificados en campo; la mayor\u00eda de empresas industriales cuentan con una infraestructura f\u00edsica, capaz de soportar esa digitalizaci\u00f3n de activos. Sin embargo, la soluci\u00f3n de comunicaci\u00f3n para lograr esa conexi\u00f3n de datos en tiempo real, deja mucho que desear\u00bb<\/em> comenta Guillermo Mir\u00f3.<\/p>\n<p style=\"text-align: left;\"><span class=\"s1\">Los sensores forman parte de una peque\u00f1a parte del mantenimiento preventivo. Si contamos con un buen sistema de recogida de datos, podremos sacarle provecho e integrarlo a las plataformas existentes en campo. <\/span>Gracias a la democratizaci\u00f3n de las tecnolog\u00edas, ahora es posible disponer con m\u00faltiples tecnolog\u00edas para llegar a ese <strong>mantenimiento 4.0.\u00a0<\/strong><\/p>\n<h2 style=\"text-align: left;\">Sistemas Hidr\u00e1ulicos y sensores<\/h2>\n<p style=\"text-align: left;\">Los sitemas hidr\u00e1ulicos est\u00e1n en todas las industrias, siendo el principal problema que presentan; la degradaci\u00f3n del aceite y la contaminaci\u00f3n externa a trav\u00e9s del agua. Como ejemplo, existen varios dispositivos que nos ayudan a controlar y medir esta contaminaci\u00f3n por agua. Consiguiendo ayudar al cliente a<strong> tomar decisiones inmediatas<\/strong>.<\/p>\n<p style=\"text-align: left;\">En consecuencia, no es necesario esperar seis meses al resultado de una muestra. Gracias a los dispositivos como sensores o sistemas de comunicaci\u00f3n inhal\u00e1mbricas permiten controlar mucho <strong>mejorar los tiempos de un proyecto de implementaci\u00f3n.\u00a0<\/strong>Siguiendo con el ejemplo de los sistemas hidr\u00e1ulicos;\u00a0 los sensores nos permiten conocer en tiempo real c\u00f3mo se est\u00e1 degradando el aceite y optimizar la vida \u00fatil del aceite (multiplicando x2 o x3 la vida del fluido). Como resultado se produce una reducci\u00f3n de costes.<\/p>\n<h3 style=\"text-align: left;\">Transmisiones mec\u00e1nicas y sensores<\/h3>\n<p style=\"text-align: left;\">El sector e\u00f3lico es el impulsor de la monitorizaci\u00f3n de las transmisiones mec\u00e1nicas. Ya consiguen adelantarse seis meses a un fallo, pasar de una parada no planificar a una planificada, mitigaci\u00f3n de fallos&#8230;<\/p>\n<p style=\"text-align: left;\"><strong>Sobre nuestro invitado: <\/strong><\/p>\n<p style=\"text-align: left;\">Guillermo Mir\u00f3, es Ingeniero Industrial egresado de la Escuela T\u00e9cnica Superior de Ingenier\u00eda Industrial (por la Universitat Polit\u00e9cnica de Valencia). Doctor en Sistemas de Propulsi\u00f3n en Medios de Transporte, en el campo de la tribolog\u00eda y la lubricaci\u00f3n en motores. <a href=\"https:\/\/www.linkedin.com\/in\/guillermo-mir%C3%B3\">Consulta aqu\u00ed su perfil de LinkedIn.<\/a><\/p>\n<p class=\"p1\" style=\"text-align: left;\">En los \u00faltimos a\u00f1os ha participado en diversos proyectos de investigaci\u00f3n relacionados con el sector de la lubricaci\u00f3n tanto a nivel estatal como a nivel internacional. Ha publicado 10 art\u00edculos en diferentes revistas cient\u00edficas y en varios congresos internacionales. Actualmente, Guillermo es Ingeniero de Aplicaciones en la empresa vasca <a href=\"https:\/\/atten2.com\/\">Atten2<\/a>.<\/p>\n<h3><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>La Digitalizaci\u00f3n de Activos Industriales Lubricados.\u00a0La sexta de las #25VoiceTalks organizadas mensualmente en la comunidad IFM.\u00a0 En este episiodio, sobre la digitalizaci\u00f3n de activos industriales lubricados, hablamos con Guillermo Mir\u00f3, sobre la influencia de la revoluci\u00f3n digital y la adopci\u00f3n de las nuevas tecnolog\u00edas. Los administradores de activos generalmente han tardado m\u00e1s en aprovechar esta [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":12974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","_wp_rev_ctl_limit":""},"categories":[785,417],"tags":[],"class_list":["post-10627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad-ifm","category-gestion-de-activos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99 &#8226; Infraspeak Blog<\/title>\n<meta name=\"description\" content=\"Digitalizaci\u00f3n de Activos Industriales Lubricados es el #6 episodio de los #25VoiceTalks powered by Infraspeak, comunidad de Mantenimiento 4.0 de Telegram.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99 &#8226; Infraspeak Blog\" \/>\n<meta property=\"og:description\" content=\"Digitalizaci\u00f3n de Activos Industriales Lubricados es el #6 episodio de los #25VoiceTalks powered by Infraspeak, comunidad de Mantenimiento 4.0 de Telegram.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/\" \/>\n<meta property=\"og:site_name\" content=\"Infraspeak Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infraspeakmaintenance\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-09T16:26:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T15:31:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/02\/IFMlogo_Talks_Blog1200x660.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"661\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Infraspeak Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infraspeak\" \/>\n<meta name=\"twitter:site\" content=\"@infraspeak\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Infraspeak Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/\"},\"author\":{\"name\":\"Infraspeak Team\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/b53887f01881a658b4cc1bf25f2d4377\"},\"headline\":\"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99\",\"datePublished\":\"2021-09-09T16:26:24+00:00\",\"dateModified\":\"2023-04-26T15:31:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/\"},\"wordCount\":720,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IFMlogo_Talks_Blog1200x660.png\",\"articleSection\":[\"Comunidad IFM\",\"Gesti\u00f3n de Activos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/\",\"name\":\"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99 &#8226; Infraspeak Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IFMlogo_Talks_Blog1200x660.png\",\"datePublished\":\"2021-09-09T16:26:24+00:00\",\"dateModified\":\"2023-04-26T15:31:14+00:00\",\"description\":\"Digitalizaci\u00f3n de Activos Industriales Lubricados es el #6 episodio de los #25VoiceTalks powered by Infraspeak, comunidad de Mantenimiento 4.0 de Telegram.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IFMlogo_Talks_Blog1200x660.png\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IFMlogo_Talks_Blog1200x660.png\",\"width\":1201,\"height\":661},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/digitalizacion-de-activos-industriales-lubricados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.infraspeak.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/\",\"name\":\"Infraspeak Blog\",\"description\":\"All About Maintenance and Facilities Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#organization\",\"name\":\"Infraspeak\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/is-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/is-logo@2x.png\",\"width\":544,\"height\":180,\"caption\":\"Infraspeak\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infraspeakmaintenance\",\"https:\\\/\\\/x.com\\\/infraspeak\",\"https:\\\/\\\/www.instagram.com\\\/infraspeak\\\/\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/infraspeak\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCOdjKyhSD9RJbRhuP-S8Avw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/b53887f01881a658b4cc1bf25f2d4377\",\"name\":\"Infraspeak Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.infraspeak.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg\",\"caption\":\"Infraspeak Team\"},\"url\":\"https:\\\/\\\/blog.infraspeak.com\\\/es\\\/author\\\/infraspeakteam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99 &#8226; Infraspeak Blog","description":"Digitalizaci\u00f3n de Activos Industriales Lubricados es el #6 episodio de los #25VoiceTalks powered by Infraspeak, comunidad de Mantenimiento 4.0 de Telegram.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/","og_locale":"es_ES","og_type":"article","og_title":"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99 &#8226; Infraspeak Blog","og_description":"Digitalizaci\u00f3n de Activos Industriales Lubricados es el #6 episodio de los #25VoiceTalks powered by Infraspeak, comunidad de Mantenimiento 4.0 de Telegram.","og_url":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/","og_site_name":"Infraspeak Blog","article_publisher":"https:\/\/www.facebook.com\/infraspeakmaintenance","article_published_time":"2021-09-09T16:26:24+00:00","article_modified_time":"2023-04-26T15:31:14+00:00","og_image":[{"width":1201,"height":661,"url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/02\/IFMlogo_Talks_Blog1200x660.png","type":"image\/png"}],"author":"Infraspeak Team","twitter_card":"summary_large_image","twitter_creator":"@infraspeak","twitter_site":"@infraspeak","twitter_misc":{"Escrito por":"Infraspeak Team","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/#article","isPartOf":{"@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/"},"author":{"name":"Infraspeak Team","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/person\/b53887f01881a658b4cc1bf25f2d4377"},"headline":"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99","datePublished":"2021-09-09T16:26:24+00:00","dateModified":"2023-04-26T15:31:14+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/"},"wordCount":720,"publisher":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/02\/IFMlogo_Talks_Blog1200x660.png","articleSection":["Comunidad IFM","Gesti\u00f3n de Activos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/","url":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/","name":"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99 &#8226; Infraspeak Blog","isPartOf":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/#primaryimage"},"image":{"@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/02\/IFMlogo_Talks_Blog1200x660.png","datePublished":"2021-09-09T16:26:24+00:00","dateModified":"2023-04-26T15:31:14+00:00","description":"Digitalizaci\u00f3n de Activos Industriales Lubricados es el #6 episodio de los #25VoiceTalks powered by Infraspeak, comunidad de Mantenimiento 4.0 de Telegram.","breadcrumb":{"@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/#primaryimage","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/02\/IFMlogo_Talks_Blog1200x660.png","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2022\/02\/IFMlogo_Talks_Blog1200x660.png","width":1201,"height":661},{"@type":"BreadcrumbList","@id":"https:\/\/blog.infraspeak.com\/es\/digitalizacion-de-activos-industriales-lubricados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.infraspeak.com\/"},{"@type":"ListItem","position":2,"name":"Digitalizaci\u00f3n de Activos Industriales Lubricados\ud83c\udf99"}]},{"@type":"WebSite","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#website","url":"https:\/\/blog.infraspeak.com\/pt-pt\/","name":"Infraspeak Blog","description":"All About Maintenance and Facilities Management","publisher":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.infraspeak.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#organization","name":"Infraspeak","url":"https:\/\/blog.infraspeak.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2018\/11\/is-logo@2x.png","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2018\/11\/is-logo@2x.png","width":544,"height":180,"caption":"Infraspeak"},"image":{"@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infraspeakmaintenance","https:\/\/x.com\/infraspeak","https:\/\/www.instagram.com\/infraspeak\/","http:\/\/www.linkedin.com\/company\/infraspeak","https:\/\/www.youtube.com\/channel\/UCOdjKyhSD9RJbRhuP-S8Avw"]},{"@type":"Person","@id":"https:\/\/blog.infraspeak.com\/pt-pt\/#\/schema\/person\/b53887f01881a658b4cc1bf25f2d4377","name":"Infraspeak Team","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","url":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","contentUrl":"https:\/\/blog.infraspeak.com\/wp-content\/uploads\/2023\/02\/296167549_2627985274000609_8314221938057526692_n-120x120.jpg","caption":"Infraspeak Team"},"url":"https:\/\/blog.infraspeak.com\/es\/author\/infraspeakteam\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/posts\/10627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/comments?post=10627"}],"version-history":[{"count":8,"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/posts\/10627\/revisions"}],"predecessor-version":[{"id":21204,"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/posts\/10627\/revisions\/21204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/media\/12974"}],"wp:attachment":[{"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/media?parent=10627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/categories?post=10627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.infraspeak.com\/es\/wp-json\/wp\/v2\/tags?post=10627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}